{"id":8252,"date":"2020-12-11T12:19:39","date_gmt":"2020-12-11T11:19:39","guid":{"rendered":"https:\/\/valtech-mobility.de\/uncategorized\/xmas-2020\/"},"modified":"2021-12-22T15:50:12","modified_gmt":"2021-12-22T14:50:12","slug":"xmas-2020","status":"publish","type":"post","link":"https:\/\/valtech-mobility.de\/en\/news\/xmas-2020\/","title":{"rendered":"Xmas 2020"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-1-percent&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7771&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text]\n<p style=\"font-size: 14px;\">Webcam on: The Valtech Mobility Pop-up Christmas Market as an online conference<\/p>\n[\/vc_column_text][vc_column_text]It goes without saying that we would have loved to all get together in person at our Christmas party, but as the saying goes: \u201dYou gotta do, what you gotta do!\u201d and so we improvised \u2013 a completely digital Christmas party with fun and games, and delicacies from all four corners of the world.<\/p>\n<p>In more than a dozen different slots not only mulled wine was being imbibed but also made \u2013 and Christmas cookies too ( using 3D printer cookie cutters): there was duck breast based on a French recipe and music covering all kinds of genres. Amazing how many hidden talents were there among us to shine and how pleasant everything felt. Even if we all hope to celebrate next year again in 3D.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;140px&#8221; bottom_padding_phone=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;newsslider newssektion bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;center&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-4-percent&#8221; column_padding_phone=&#8221;padding-4-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;More news&#8221; font_container=&#8221;tag:h2|text_align:center|color:%2312120f&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1640177733086{margin-bottom: 30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-1-percent&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_phone=&#8221;-50px&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]\n        \n\t\t\t<div class=\"row blog-recent columns-2\" data-style=\"classic_enhanced\" data-color-scheme=\"light\" data-remove-post-date=\"\" data-remove-post-author=\"1\" data-remove-post-comment-number=\"1\" data-remove-post-nectar-love=\"1\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-23281 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-23281 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/strategic-move-valtech-mobility-appoints-connected-car-pioneer-andrea-sroczynski-as-svp-of-strategic-growth\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/strategic-move-valtech-mobility-appoints-connected-car-pioneer-andrea-sroczynski-as-svp-of-strategic-growth\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"23281\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 17. March 2026 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Strategic Move: Valtech Mobility Appoints Connected Car Pioneer Andrea Sroczynski as SVP of Strategic Growth<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tStrategic Move: Valtech Mobility Appoints Connected Car Pioneer Andrea Sroczynski as SVP of Strategic Growth Munich, \u2013 Valtech Mobility is setting the course for a new phase of global growth:&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-22725 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-22725 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/nexus-verffentlichung-des-ersten-release\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/nexus-verffentlichung-des-ersten-release\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"22725\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 11. February 2026 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">NEXUS: Ver\u00f6ffentlichung des ersten Release<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tNEXUS: Publication of the first release Last year at the IAA, we announced our partnership with Google Cloud and the joint collaboration on the open source and AI-native platform for&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-21753 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-21753 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/valtech-mobility-und-autocrypt-schliessen-partnerschaft\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/valtech-mobility-und-autocrypt-schliessen-partnerschaft\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"21753\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 23. September 2025 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Valtech Mobility und Autocrypt schlie\u00dfen Partnerschaft<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tValtech Mobility and Autocrypt enter into partnership At the IAA, Valtech Mobility signed a partnership agreement with AUTOCRYPT, a leading provider of cybersecurity and digital key solutions for the automotive&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-21444 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-21444 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/kunden-und-partnerstimmen-so-veraendert-ai-die-industrie\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/kunden-und-partnerstimmen-so-veraendert-ai-die-industrie\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"21444\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 13. August 2025 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Kunden und Partnerstimmen: So ver\u00e4ndert AI die Industrie<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tKunden und Partnerstimmen: So ver\u00e4ndert AI die Industrie Im Rahmen unseres Netzwerk Events Anfang Juli hatten wir die M\u00f6glichkeit einige unserer Kunden und Partner zu interviewen. Die Interviews standen dabei,&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t<\/div><!--\/blog-recent-->\n\t\t\n\t\t\n<div style=\"display: none;\">[recent_posts style=&#8221;classic_enhanced&#8221; color_scheme=&#8221;light&#8221; columns=&#8221;2&#8243; category=&#8221;news&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; blog_remove_post_nectar_love=&#8221;true&#8221; posts_per_page=&#8221;4&#8243;]<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-8252","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xmas 2020 - Valtech Mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xmas 2020 - Valtech Mobility\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Valtech Mobility\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-11T11:19:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-22T14:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Entwicklung\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Entwicklung\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/\"},\"author\":{\"name\":\"Entwicklung\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/0ec64af1094c2fdba3906b66aa645e6c\"},\"headline\":\"Xmas 2020\",\"datePublished\":\"2020-12-11T11:19:39+00:00\",\"dateModified\":\"2021-12-22T14:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/\"},\"wordCount\":905,\"image\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/\",\"name\":\"Xmas 2020 - Valtech Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg\",\"datePublished\":\"2020-12-11T11:19:39+00:00\",\"dateModified\":\"2021-12-22T14:50:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/0ec64af1094c2fdba3906b66aa645e6c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/xmas-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xmas 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/\",\"name\":\"Valtech Mobility\",\"description\":\"Some Cars Are Smarter Than Others.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valtech-mobility.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/0ec64af1094c2fdba3906b66aa645e6c\",\"name\":\"Entwicklung\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/author\\\/omsag_dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xmas 2020 - Valtech Mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/","og_locale":"en_US","og_type":"article","og_title":"Xmas 2020 - Valtech Mobility","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/","og_site_name":"Valtech Mobility","article_published_time":"2020-12-11T11:19:39+00:00","article_modified_time":"2021-12-22T14:50:12+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg","type":"image\/jpeg"}],"author":"Entwicklung","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Entwicklung","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#article","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/"},"author":{"name":"Entwicklung","@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/0ec64af1094c2fdba3906b66aa645e6c"},"headline":"Xmas 2020","datePublished":"2020-12-11T11:19:39+00:00","dateModified":"2021-12-22T14:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/"},"wordCount":905,"image":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/","url":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/","name":"Xmas 2020 - Valtech Mobility","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#primaryimage"},"image":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg","datePublished":"2020-12-11T11:19:39+00:00","dateModified":"2021-12-22T14:50:12+00:00","author":{"@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/0ec64af1094c2fdba3906b66aa645e6c"},"breadcrumb":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#primaryimage","url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg","contentUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2020\/12\/remote-weihnachtsfeier-kollage-news-grid-scaled-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/xmas-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/valtech-mobility.de\/en\/"},{"@type":"ListItem","position":2,"name":"Xmas 2020"}]},{"@type":"WebSite","@id":"https:\/\/valtech-mobility.de\/#website","url":"https:\/\/valtech-mobility.de\/","name":"Valtech Mobility","description":"Some Cars Are Smarter Than Others.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valtech-mobility.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/0ec64af1094c2fdba3906b66aa645e6c","name":"Entwicklung","url":"https:\/\/valtech-mobility.de\/en\/author\/omsag_dev\/"}]}},"_links":{"self":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts\/8252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/comments?post=8252"}],"version-history":[{"count":0,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts\/8252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media\/8050"}],"wp:attachment":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media?parent=8252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/categories?post=8252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/tags?post=8252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}