{"id":10939,"date":"2022-10-11T14:01:58","date_gmt":"2022-10-11T12:01:58","guid":{"rendered":"https:\/\/valtech-mobility.de\/uncategorized\/it-connect-copy\/"},"modified":"2023-01-19T09:35:01","modified_gmt":"2023-01-19T08:35:01","slug":"autotecheurope","status":"publish","type":"post","link":"https:\/\/valtech-mobility.de\/en\/news\/autotecheurope\/","title":{"rendered":"AutoTech: Europe"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;overlayleft newsdetail blue&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;0&#8243; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-1-percent&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;10935&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; top_padding_phone=&#8221;70px&#8221; bottom_padding_phone=&#8221;70px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1665491072596{padding-top: 40px !important;padding-bottom: 50px !important;}&#8221;]On November 15th and 16th we will be part of the AutoTech: Europe trade show in Munich.<br \/>\nAt the core of the industry trade show is the topic of transformation of the automotive industry. With over 500 attendees and 75 speakers, the show has a strong IT focus, and we are excited to be a part of it.<\/p>\n<p><strong>Save the Date:<\/strong><\/p>\n<p>November 15th + 16th<\/p>\n<p>Leonardo Royal Hotel Munich, Moosacher Str. 90[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;valbtn blue&#8221; text=&#8221;To the Event&#8221; url=&#8221;https:\/\/wardsauto.informa.com\/autotech-europe\/&#8221; margin_top=&#8221;0px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;140px&#8221; bottom_padding_phone=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;newsslider newssektion bg-z4 lightsection&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;center&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-4-percent&#8221; column_padding_phone=&#8221;padding-4-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;More News&#8221; font_container=&#8221;tag:h2|text_align:center|color:%2312120f&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_16353388606{margin-bottom: 30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; min_width_desktop=&#8221;10&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-1-percent&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_phone=&#8221;-50px&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]\n        \n\t\t\t<div class=\"row blog-recent columns-2\" data-style=\"classic_enhanced\" data-color-scheme=\"light\" data-remove-post-date=\"\" data-remove-post-author=\"1\" data-remove-post-comment-number=\"1\" data-remove-post-nectar-love=\"1\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-23281 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-23281 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/strategic-move-valtech-mobility-appoints-connected-car-pioneer-andrea-sroczynski-as-svp-of-strategic-growth\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/03\/andrea-news-beitrag-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/strategic-move-valtech-mobility-appoints-connected-car-pioneer-andrea-sroczynski-as-svp-of-strategic-growth\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"23281\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 17. March 2026 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Strategic Move: Valtech Mobility Appoints Connected Car Pioneer Andrea Sroczynski as SVP of Strategic Growth<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tStrategic Move: Valtech Mobility Appoints Connected Car Pioneer Andrea Sroczynski as SVP of Strategic Growth Munich, \u2013 Valtech Mobility is setting the course for a new phase of global growth:&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-22725 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-22725 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/nexus-verffentlichung-des-ersten-release\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2026\/02\/nexus-release-beitrag-1-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/nexus-verffentlichung-des-ersten-release\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"22725\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 11. February 2026 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">NEXUS: Ver\u00f6ffentlichung des ersten Release<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tNEXUS: Publication of the first release Last year at the IAA, we announced our partnership with Google Cloud and the joint collaboration on the open source and AI-native platform for&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-21753 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-21753 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/valtech-mobility-und-autocrypt-schliessen-partnerschaft\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/09\/beitrag-autocrypt-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/valtech-mobility-und-autocrypt-schliessen-partnerschaft\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"21753\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 23. September 2025 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Valtech Mobility und Autocrypt schlie\u00dfen Partnerschaft<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tValtech Mobility and Autocrypt enter into partnership At the IAA, Valtech Mobility signed a partnership agreement with AUTOCRYPT, a leading provider of cybersecurity and digital key solutions for the automotive&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"col span_6 post-21444 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\" >\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap post-21444 post type-post status-publish format-standard has-post-thumbnail category-news tag-news-en\">\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/valtech-mobility.de\/en\/news\/kunden-und-partnerstimmen-so-veraendert-ai-die-industrie\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"403\" src=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-600x403.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1600px) 50vw, (min-width: 1300px) 50vw, (min-width: 1000px) 50vw, (min-width: 690px) 100vw, 100vw\" srcset=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-600x403.jpg 600w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-900x604.jpg 900w, https:\/\/valtech-mobility.de\/wp-content\/uploads\/2025\/08\/beitrag-ai-interviews-400x269.jpg 400w\" \/><\/span><\/a>\n<a class=\"entire-meta-link\" href=\"https:\/\/valtech-mobility.de\/en\/news\/kunden-und-partnerstimmen-so-veraendert-ai-die-industrie\/\" ><\/a>\t\n\n\t\t\t\t\t\t\t<div class=\"article-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"post-header\">\n                  <div class=\"metawrapper\">\n                  <span class=\"meta-category\"><a class=\"news-en \" data-id=\"21444\" data-categories=\"Array\n(\n    [0] => WP_Term Object\n        (\n            [term_id] => 108\n            [name] => News\n            [slug] => news-en\n            [term_group] => 0\n            [term_taxonomy_id] => 108\n            [taxonomy] => post_tag\n            [description] => \n            [parent] => 0\n            [count] => 57\n            [filter] => raw\n        )\n\n)\n\" href=\"https:\/\/valtech-mobility.de\/en\/tag\/news-en\/\">News<\/a><\/span>\n                      \n  \t\t\t\t\t\t\t\t\t<span class=\"meta\"> 13. August 2025 <\/span> \n                  <\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Kunden und Partnerstimmen: So ver\u00e4ndert AI die Industrie<\/h3>\t\n\t\t\t\t\t\t\t\t<\/div><!--\/post-header-->\n\t\t\t\t\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t\t\t\t\tKunden und Partnerstimmen: So ver\u00e4ndert AI die Industrie Im Rahmen unseres Netzwerk Events Anfang Juli hatten wir die M\u00f6glichkeit einige unserer Kunden und Partner zu interviewen. Die Interviews standen dabei,&hellip;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"meta-author\"> <a href=\"https:\/\/valtech-mobility.de\/en\/author\/jannik\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> Jannik Frank<\/a> <\/span> \n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"nectar-love-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/nectar-love-wrap-->\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t<\/div><!--\/blog-recent-->\n\t\t\n\t\t\n<div style=\"display: none;\" class=\"valtechrecentpostwrapper\">[recent_posts style=&#8221;classic_enhanced&#8221; color_scheme=&#8221;light&#8221; columns=&#8221;2&#8243; category=&#8221;news&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; blog_remove_post_nectar_love=&#8221;true&#8221; posts_per_page=&#8221;4&#8243;]<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;overlayleft newsdetail blue&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;&#8230;<\/p>\n","protected":false},"author":9,"featured_media":10934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[65,24],"tags":[51,108],"class_list":{"0":"post-10939","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-events","8":"category-news","9":"tag-events-en","10":"tag-news-en"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AutoTech: Europe - Valtech Mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AutoTech: Europe - Valtech Mobility\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;overlayleft newsdetail blue&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/\" \/>\n<meta property=\"og:site_name\" content=\"Valtech Mobility\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-11T12:01:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-19T08:35:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/01\/7b6346d2f1edd2e112cc2acdbfd322839dd68af1fa47bb5234d935335c04c3cc-rimg-w526-h296-gmir.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julius Heigl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julius Heigl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/\"},\"author\":{\"name\":\"Julius Heigl\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/31b648761b4d12747b9664d222065584\"},\"headline\":\"AutoTech: Europe\",\"datePublished\":\"2022-10-11T12:01:58+00:00\",\"dateModified\":\"2023-01-19T08:35:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/\"},\"wordCount\":1412,\"image\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/autotech-europe-banner-200x90-1.png\",\"keywords\":[\"Events\",\"News\"],\"articleSection\":[\"Events\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/\",\"name\":\"AutoTech: Europe - Valtech Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/autotech-europe-banner-200x90-1.png\",\"datePublished\":\"2022-10-11T12:01:58+00:00\",\"dateModified\":\"2023-01-19T08:35:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/31b648761b4d12747b9664d222065584\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/autotech-europe-banner-200x90-1.png\",\"contentUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/autotech-europe-banner-200x90-1.png\",\"width\":200,\"height\":90},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/news-en\\\/autotecheurope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AutoTech: Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/\",\"name\":\"Valtech Mobility\",\"description\":\"Some Cars Are Smarter Than Others.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valtech-mobility.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#\\\/schema\\\/person\\\/31b648761b4d12747b9664d222065584\",\"name\":\"Julius Heigl\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/author\\\/jheigl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AutoTech: Europe - Valtech Mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/","og_locale":"en_US","og_type":"article","og_title":"AutoTech: Europe - Valtech Mobility","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;overlayleft newsdetail blue&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;...","og_url":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/","og_site_name":"Valtech Mobility","article_published_time":"2022-10-11T12:01:58+00:00","article_modified_time":"2023-01-19T08:35:01+00:00","og_image":[{"width":526,"height":296,"url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/01\/7b6346d2f1edd2e112cc2acdbfd322839dd68af1fa47bb5234d935335c04c3cc-rimg-w526-h296-gmir.jpeg","type":"image\/jpeg"}],"author":"Julius Heigl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Julius Heigl","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#article","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/"},"author":{"name":"Julius Heigl","@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/31b648761b4d12747b9664d222065584"},"headline":"AutoTech: Europe","datePublished":"2022-10-11T12:01:58+00:00","dateModified":"2023-01-19T08:35:01+00:00","mainEntityOfPage":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/"},"wordCount":1412,"image":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#primaryimage"},"thumbnailUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/10\/autotech-europe-banner-200x90-1.png","keywords":["Events","News"],"articleSection":["Events","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/","url":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/","name":"AutoTech: Europe - Valtech Mobility","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#primaryimage"},"image":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#primaryimage"},"thumbnailUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/10\/autotech-europe-banner-200x90-1.png","datePublished":"2022-10-11T12:01:58+00:00","dateModified":"2023-01-19T08:35:01+00:00","author":{"@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/31b648761b4d12747b9664d222065584"},"breadcrumb":{"@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#primaryimage","url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/10\/autotech-europe-banner-200x90-1.png","contentUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2022\/10\/autotech-europe-banner-200x90-1.png","width":200,"height":90},{"@type":"BreadcrumbList","@id":"https:\/\/valtech-mobility.de\/en\/news-en\/autotecheurope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/valtech-mobility.de\/en\/"},{"@type":"ListItem","position":2,"name":"AutoTech: Europe"}]},{"@type":"WebSite","@id":"https:\/\/valtech-mobility.de\/#website","url":"https:\/\/valtech-mobility.de\/","name":"Valtech Mobility","description":"Some Cars Are Smarter Than Others.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valtech-mobility.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/valtech-mobility.de\/#\/schema\/person\/31b648761b4d12747b9664d222065584","name":"Julius Heigl","url":"https:\/\/valtech-mobility.de\/en\/author\/jheigl\/"}]}},"_links":{"self":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts\/10939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/comments?post=10939"}],"version-history":[{"count":0,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts\/10939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media\/10934"}],"wp:attachment":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media?parent=10939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/categories?post=10939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/tags?post=10939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}