{"id":18790,"date":"2024-01-01T07:00:03","date_gmt":"2024-01-01T06:00:03","guid":{"rendered":"https:\/\/valtech-mobility.de\/cases\/apple-spotify-integration\/"},"modified":"2026-09-01T16:27:03","modified_gmt":"2026-09-01T14:27:03","slug":"apple-spotify-integration","status":"publish","type":"page","link":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/","title":{"rendered":"Apple &amp; Spotify Integration"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffef7a&#8221; bg_image=&#8221;16976&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;colReverse h640 dflex&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;colReverse&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Porsche&#8221; font_container=&#8221;tag:p|font_size:24px|text_align:left|color:%23ffffff|line_height:32px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221; el_class=&#8221;text&#8221;][vc_custom_heading text=&#8221;Apple Music &amp; Spotify Integration&#8221; font_container=&#8221;tag:h1|font_size:64px|text_align:left|color:%23ffffff|line_height:80px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;200px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;200px&#8221; left_padding_desktop=&#8221;200&#8243; right_padding_desktop=&#8221;200&#8243; top_padding_tablet=&#8221;100px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;100px&#8221; left_padding_tablet=&#8221;20px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;20px&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;The all-electric Porsche Taycan has both Apple Music and Spotify on board as a fully integrated music streaming function.&#8221; font_container=&#8221;tag:h4|font_size:40px|text_align:left|color:%2312120f|line_height:56px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#12120f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;200px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;200px&#8221; left_padding_desktop=&#8221;200&#8243; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;200&#8243; top_padding_tablet=&#8221;100px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;100px&#8221; left_padding_tablet=&#8221;20px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;20px&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;videoteaser&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;darkButton&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_video_lightbox link_style=&#8221;play_button_2&#8243; nectar_play_button_color=&#8221;Extra-Color-3&#8243; image_url=&#8221;12154&#8243; hover_effect=&#8221;defaut&#8221; box_shadow=&#8221;none&#8221; border_radius=&#8221;none&#8221; play_button_size=&#8221;default&#8221; video_url=&#8221;\/wp-content\/uploads\/2023\/01\/porsch-feat-spotify-final.mp4&#8243; image_size=&#8221;large&#8221;][vc_custom_heading text=&#8221;&#8220;Hey Porsche, play AC\/DC&#8220;&#8221; font_container=&#8221;tag:p|font_size:24px|text_align:center|color:%23ffffff|line_height:32px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221; el_class=&#8221;text&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f2ef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;100px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Results&#8221; font_container=&#8221;tag:h4|font_size:40px|text_align:left|color:%2312120f|line_height:56px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner top_padding_desktop=&#8221;24px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;24px&#8221; left_padding_desktop=&#8221;20px&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;h295&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;17141&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_custom_heading text=&#8221;Streaming without a smartphone&#8221; font_container=&#8221;tag:p|font_size:24px|text_align:left|color:%2312120f|line_height:32px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723810451817{padding-bottom: 15px !important;}&#8221; el_class=&#8221;text&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;24px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;24px&#8221; left_padding_desktop=&#8221;20px&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;h295&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;100&#8243;][image_with_animation image_url=&#8221;17138&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_custom_heading text=&#8221;Exclusive functionalities&#8221; font_container=&#8221;tag:p|font_size:24px|text_align:left|color:%2312120f|line_height:32px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723810464046{padding-bottom: 15px !important;}&#8221; el_class=&#8221;text&#8221;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;24px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;24px&#8221; left_padding_desktop=&#8221;20px&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;h295&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;200&#8243;][image_with_animation image_url=&#8221;17135&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_custom_heading text=&#8221;Link via QR code&#8221; font_container=&#8221;tag:p|font_size:24px|text_align:left|color:%2312120f|line_height:32px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723810475141{padding-bottom: 15px !important;}&#8221; el_class=&#8221;text&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f2ef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;max1920&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;16509&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;640px&#8221; custom_height_tablet=&#8221;400px&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Our Role&#8221; font_container=&#8221;tag:h4|font_size:40px|text_align:left|color:%2312120f|line_height:56px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"wpb_text_column wpb_content_element vc_custom_1634806976480\">\n<div class=\"wpb_wrapper\">\n<p>Valtech Mobility was an integral part of the development of the vehicle app for the integration of Apple Music.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element vc_custom_1634806982840\">\n<div class=\"wpb_wrapper\">\n<p>An agile mixed team (with Apple and Porsche) worked together to implement the functionalities. These include the simple linking of the Apple account with the Porsche ID via a QR code (displayed in the vehicle UI), browsing content from the Apple music library and streaming tracks and radio stations.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#f3f2ef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;max1920&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Exclusive Functionalities&#8221; font_container=&#8221;tag:h4|font_size:40px|text_align:left|color:%2312120f|line_height:56px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Thanks to the deep integration, functionalities are possible that were previously not feasible, e.g. adding tracks played on FM radio to the respective Apple Music library or playing a playlist inspired by FM radio tracks.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;18546&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;640px&#8221; custom_height_tablet=&#8221;400px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;44&#8243; custom_height_tablet=&#8221;22&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#c6c2ff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; bottom_padding=&#8221;80px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Contact us&#8221; font_container=&#8221;tag:div|font_size:40px|text_align:left|line_height:48px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<noscript class=\"ninja-forms-noscript-message\">\n\tNotice: JavaScript is required for this content.<\/noscript>\n<style>\n\n        \/* PLUGIN WIDE STYLES *\/\n    \n        .nf-form-content .nf-field-element .ninja-forms-field:not(select) {\n                                    background-color:#ffffff;\n                    }\n    <\/style><style>\n\n        \/* FIELDS STYLES *\/\n    \n        .nf-form-content .nf-field-container #nf-field-161-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-163-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-165-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-162-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-164-wrap .nf-field-label label {\n                                            display: none;                    }\n        .nf-form-content .nf-field-container #nf-field-164-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-189-wrap .nf-field-element .ninja-forms-field {\n                                            border-bottom: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-167-wrap .nf-field-element .ninja-forms-field {\n                                            border: 2px solid #000000; border-radius: 0; background: transparent;                    }\n        .nf-form-content .nf-field-container #nf-field-170-wrap .nf-field-element .ninja-forms-field {\n                                    background-color:#12120f;\n                                            color:#ffffff;\n                                            font-size:28px;\n                    }\n    <\/style><div id=\"nf-form-11-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-11\" aria-describedby=\"nf-form-errors-11\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='11';form.settings={\"ninjaForms\":\"Ninja Forms\",\"changeEmailErrorMsg\":\"Please enter a valid email address!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"These fields must match!\",\"fieldNumberNumMinError\":\"Number Min Error\",\"fieldNumberNumMaxError\":\"Number Max Error\",\"fieldNumberIncrementBy\":\"Please increment by \",\"fieldTextareaRTEInsertLink\":\"Insert Link\",\"fieldTextareaRTEInsertMedia\":\"Insert Media\",\"fieldTextareaRTESelectAFile\":\"Select a file\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Dismiss\",\"insertLink\":\"Insert Link\",\"formErrorsCorrectErrors\":\"Before submitting the form, make sure you correct any errors.\",\"formHoneypot\":\"If you are a human seeing this field, please leave it empty.\",\"validateRequiredField\":\"This is a required field.\",\"honeypotHoneypotError\":\"Honeypot Error\",\"fileUploadOldCodeFileUploadInProgress\":\"File Upload in Progress.\",\"fileUploadOldCodeFileUpload\":\"FILE UPLOAD\",\"currencySymbol\":\"&#36;\",\"fieldsMarkedRequired\":\"Bitte f\\u00fcllen Sie alle Pflichtfelder aus.\",\"thousands_sep\":\",\",\"decimal_point\":\".\",\"siteLocale\":\"en_US\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"of\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"Contact us\",\"show_title\":0,\"allow_public_link\":0,\"embed_form\":\"\",\"clear_complete\":1,\"hide_complete\":1,\"default_label_pos\":\"above\",\"wrapper_class\":\"\",\"element_class\":\"\",\"form_title_heading_level\":\"3\",\"key\":\"\",\"add_submit\":0,\"currency\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"logged_in\":false,\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"The form has reached its contribution limit.\",\"calculations\":[],\"container_styles_show_advanced_css\":0,\"title_styles_show_advanced_css\":0,\"row_styles_show_advanced_css\":0,\"row-odd_styles_show_advanced_css\":0,\"success-msg_styles_show_advanced_css\":0,\"error_msg_styles_show_advanced_css\":0,\"formContentData\":[{\"order\":1,\"cells\":[{\"order\":0,\"fields\":[\"vorname_1728474189405\"],\"width\":33},{\"order\":1,\"fields\":[\"nachname_1727096814797\"],\"width\":33},{\"order\":2,\"fields\":[\"email_1720699393153\"],\"width\":33}]},{\"order\":2,\"cells\":[{\"order\":0,\"fields\":[\"firmenname_1727096820411\"],\"width\":33},{\"order\":1,\"fields\":[\"branche_1727355221170\"],\"width\":33},{\"order\":2,\"fields\":[\"land_1727096886546\"],\"width\":33}]},{\"order\":4,\"cells\":[{\"order\":0,\"fields\":[\"deine_nachricht_1727096835129\"],\"width\":\"100\"}]},{\"order\":5,\"cells\":[{\"order\":0,\"fields\":[\"ich_bin_damit_einverstanden_relevante_nachrichten_und_marketingmitteilungen_von_valtech_mobility_zu_erhalten_less_than_br_greater_than_ich_bin_mir_bewusst_dass_ich_mich_jederzeit_wieder_abmelden_kann_fuer_weitere_informationen_besuchen_sie_bitte_unsere_less_than_a_href_datenschutz_greater_than_datenschutzerklaerung_less_than_a_greater_than_1727355939945\"],\"width\":\"100\"}]},{\"order\":6,\"cells\":[{\"order\":0,\"fields\":[\"kontaktieren_sie_uns_1727097870264\"],\"width\":\"100\"}]}],\"drawerDisabled\":false,\"container_styles_background-color\":\"\",\"container_styles_border\":\"\",\"container_styles_height\":\"\",\"container_styles_margin\":\"\",\"container_styles_padding\":\"\",\"container_styles_float\":\"\",\"title_styles_border\":\"\",\"title_styles_height\":\"\",\"title_styles_width\":\"\",\"title_styles_font-size\":\"\",\"title_styles_margin\":\"\",\"title_styles_padding\":\"\",\"title_styles_float\":\"\",\"row_styles_border\":\"\",\"row_styles_width\":\"\",\"row_styles_font-size\":\"\",\"row_styles_margin\":\"\",\"row_styles_padding\":\"\",\"row-odd_styles_border\":\"\",\"row-odd_styles_height\":\"\",\"row-odd_styles_width\":\"\",\"row-odd_styles_font-size\":\"\",\"row-odd_styles_margin\":\"\",\"row-odd_styles_padding\":\"\",\"success-msg_styles_border\":\"\",\"success-msg_styles_height\":\"\",\"success-msg_styles_width\":\"\",\"success-msg_styles_font-size\":\"\",\"success-msg_styles_margin\":\"\",\"success-msg_styles_padding\":\"\",\"error_msg_styles_border\":\"\",\"error_msg_styles_width\":\"\",\"error_msg_styles_font-size\":\"\",\"error_msg_styles_margin\":\"\",\"error_msg_styles_padding\":\"\",\"public_link\":\"https:\\\/\\\/valtech-mobility.de\\\/ninja-forms\\\/11ini8\",\"public_link_key\":\"11ini8\",\"objectDomain\":\"display\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":1,\"idAttribute\":\"id\",\"type\":\"textbox\",\"label\":\"First name\",\"key\":\"vorname_1728474189405\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"\",\"personally_identifiable\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3818\",\"value\":\"\",\"element_styles_background-color\":\"\",\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"drawerDisabled\":false,\"id\":161,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":2,\"idAttribute\":\"id\",\"type\":\"textbox\",\"label\":\"Surname\",\"key\":\"nachname_1727096814797\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"\",\"personally_identifiable\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3821\",\"value\":\"\",\"cellOrder\":1,\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"id\":163,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"type\":\"email\",\"label\":\"e-mail\",\"key\":\"email_1720699393153\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"wrap_styles_show_advanced_css\":0,\"label_styles_show_advanced_css\":0,\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3823\",\"value\":\"\",\"cellOrder\":1,\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"drawerDisabled\":false,\"id\":165,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"type\":\"textbox\",\"label\":\"Company name\",\"key\":\"firmenname_1727096820411\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"\",\"personally_identifiable\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3826\",\"value\":\"\",\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"id\":162,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"type\":\"listselect\",\"label\":\"Industry\",\"key\":\"branche_1727355221170\",\"label_pos\":\"above\",\"required\":false,\"options\":[{\"errors\":[],\"max_options\":0,\"order\":0,\"new\":false,\"options\":[],\"label\":\"Select industry\",\"value\":\"0\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"label\":\"Mobility\",\"value\":\"mobilitaet\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Charity\",\"value\":\"wohltaetigkeit\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Education\",\"value\":\"bildung\",\"calc\":\"\",\"selected\":0,\"order\":3,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":4,\"new\":false,\"options\":[],\"label\":\"Consumer goods\",\"value\":\"vier\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":5,\"new\":false,\"options\":[],\"label\":\"Distribution\",\"value\":\"fuenf\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":6,\"new\":false,\"options\":[],\"label\":\"Financial Services\",\"value\":\"sechs\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":7,\"new\":false,\"options\":[],\"label\":\"Government \\\/ Public\",\"value\":\"sieben\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":8,\"new\":false,\"options\":[],\"label\":\"Health\",\"value\":\"acht\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":9,\"new\":false,\"options\":[],\"label\":\"Luxury\",\"value\":\"neun\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":10,\"new\":false,\"options\":[],\"label\":\"Production\",\"value\":\"zehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":11,\"new\":false,\"options\":[],\"label\":\"Media\",\"value\":\"elf\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":12,\"new\":false,\"options\":[],\"label\":\"Other services\",\"value\":\"zwoelf\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":13,\"new\":false,\"options\":[],\"label\":\"Real estate\",\"value\":\"dreizehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":14,\"new\":false,\"options\":[],\"label\":\"Sale\",\"value\":\"vierzehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":15,\"new\":false,\"options\":[],\"label\":\"Technology\",\"value\":\"fuenfzehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":16,\"new\":false,\"options\":[],\"label\":\"Telecommunications\",\"value\":\"sechzehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":17,\"new\":false,\"options\":[],\"label\":\"Journey\",\"value\":\"siebzehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true},{\"errors\":[],\"max_options\":0,\"order\":18,\"new\":false,\"options\":[],\"label\":\"Supply\",\"value\":\"achtzehn\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}},\"manual_value\":true}],\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":1,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3828\",\"cellOrder\":2,\"drawerDisabled\":false,\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"label_styles_advanced\":\"display: none;\",\"id\":164,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"Country\",\"type\":\"textbox\",\"cellcid\":\"c3830\",\"key\":\"land_1727096886546\",\"label_pos\":\"above\",\"required\":false,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"\",\"personally_identifiable\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"element_styles_advanced\":\"border-bottom: 2px solid #000000; border-radius: 0; background: transparent;\",\"value\":\"\",\"cellOrder\":3,\"drawerDisabled\":false,\"id\":189,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"type\":\"textarea\",\"label\":\"Your message\",\"key\":\"deine_nachricht_1727096835129\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"val-label-animation\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":1,\"cellcid\":\"c3833\",\"value\":\"\",\"element_styles_advanced\":\"border: 2px solid #000000; border-radius: 0; background: transparent;\",\"drawerDisabled\":false,\"id\":167,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"type\":\"checkbox\",\"label\":\"I agree to receive relevant news and marketing communications from Valtech Mobility.  <br>  I am aware that I can unsubscribe at any time. For more information, please visit our <a href=\\\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/privacy-policy\\\/\\\">privacy policy<\\\/a>. \",\"key\":\"ich_bin_damit_einverstanden_relevante_nachrichten_und_marketingmitteilungen_von_valtech_mobility_zu_erhalten_less_than_br_greater_than_ich_bin_mir_bewusst_dass_ich_mich_jederzeit_wieder_abmelden_kann_fuer_weitere_informationen_besuchen_sie_bitte_unsere_less_than_a_href_datenschutz_greater_than_datenschutzerklaerung_less_than_a_greater_than_1727355939945\",\"label_pos\":\"right\",\"required\":false,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":false,\"admin_label\":\"\",\"help_text\":\"<p><br><\\\/p>\",\"default_value\":\"unchecked\",\"checked_value\":\"Ausgew\\u00e4hlt\",\"unchecked_value\":\"Nicht ausgew\\u00e4hlt\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"label_styles_border\":\"\",\"label_styles_width\":\"\",\"label_styles_font-size\":\"\",\"label_styles_margin\":\"\",\"label_styles_padding\":\"\",\"label_styles_float\":\"\",\"label_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":0,\"cellcid\":\"c3836\",\"drawerDisabled\":false,\"id\":169,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Get in touch with us\",\"processing_label\":\"Being processed\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"kontaktieren_sie_uns_1727097870264\",\"wrap_styles_border\":\"\",\"wrap_styles_width\":\"\",\"wrap_styles_margin\":\"\",\"wrap_styles_padding\":\"\",\"wrap_styles_float\":\"\",\"wrap_styles_show_advanced_css\":0,\"element_styles_border\":\"\",\"element_styles_width\":\"\",\"element_styles_font-size\":\"28px\",\"element_styles_margin\":\"\",\"element_styles_padding\":\"\",\"element_styles_float\":\"\",\"element_styles_show_advanced_css\":0,\"submit_element_hover_styles_border\":\"\",\"submit_element_hover_styles_width\":\"\",\"submit_element_hover_styles_font-size\":\"\",\"submit_element_hover_styles_margin\":\"\",\"submit_element_hover_styles_padding\":\"\",\"submit_element_hover_styles_float\":\"\",\"submit_element_hover_styles_show_advanced_css\":0,\"cellcid\":\"c3839\",\"drawerDisabled\":false,\"element_styles_background-color\":\"#12120f\",\"element_styles_color\":\"#ffffff\",\"admin_label\":\"\",\"id\":170,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n                <script id=\"nf-tmpl-cell\" type=\"text\/template\">\n            <nf-fields><\/nf-fields>\n        <\/script>\n\n        <script id=\"nf-tmpl-row\" type=\"text\/template\">\n            <nf-cells><\/nf-cells>\n        <\/script>\n\n        [\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffef7a&#8221; bg_image=&#8221;16976&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;colReverse h640 dflex&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221;&#8230;<\/p>\n","protected":false},"author":14,"featured_media":16652,"parent":18762,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_exclude_from_search":false,"footnotes":""},"seitenkategorie":[130],"topic":[],"class_list":["post-18790","page","type-page","status-publish","has-post-thumbnail","seitenkategorie-in-car-experience-en-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apple &amp; Spotify Integration - Valtech Mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple &amp; Spotify Integration - Valtech Mobility\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffef7a&#8221; bg_image=&#8221;16976&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;colReverse h640 dflex&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/\" \/>\n<meta property=\"og:site_name\" content=\"Valtech Mobility\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2024\/08\/spotify.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"962\" \/>\n\t<meta property=\"og:image:height\" content=\"1002\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/\",\"name\":\"Apple &amp; Spotify Integration - Valtech Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/spotify.jpg\",\"datePublished\":\"2024-01-01T06:00:03+00:00\",\"dateModified\":\"2026-09-01T14:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/spotify.jpg\",\"contentUrl\":\"https:\\\/\\\/valtech-mobility.de\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/spotify.jpg\",\"width\":962,\"height\":1002},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/apple-spotify-integration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cases\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/cases\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Apple &amp; Spotify Integration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/\",\"name\":\"Valtech Mobility\",\"description\":\"Some Cars Are Smarter Than Others.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valtech-mobility.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apple &amp; Spotify Integration - Valtech Mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/","og_locale":"en_US","og_type":"article","og_title":"Apple &amp; Spotify Integration - Valtech Mobility","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffef7a&#8221; bg_image=&#8221;16976&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;colReverse h640 dflex&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221;...","og_url":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/","og_site_name":"Valtech Mobility","article_modified_time":"2026-09-01T14:27:03+00:00","og_image":[{"width":962,"height":1002,"url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2024\/08\/spotify.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/","url":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/","name":"Apple &amp; Spotify Integration - Valtech Mobility","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/#primaryimage"},"image":{"@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/#primaryimage"},"thumbnailUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2024\/08\/spotify.jpg","datePublished":"2024-01-01T06:00:03+00:00","dateModified":"2026-09-01T14:27:03+00:00","breadcrumb":{"@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/#primaryimage","url":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2024\/08\/spotify.jpg","contentUrl":"https:\/\/valtech-mobility.de\/wp-content\/uploads\/2024\/08\/spotify.jpg","width":962,"height":1002},{"@type":"BreadcrumbList","@id":"https:\/\/valtech-mobility.de\/en\/cases\/apple-spotify-integration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/valtech-mobility.de\/en\/"},{"@type":"ListItem","position":2,"name":"Cases","item":"https:\/\/valtech-mobility.de\/en\/cases\/"},{"@type":"ListItem","position":3,"name":"Apple &amp; Spotify Integration"}]},{"@type":"WebSite","@id":"https:\/\/valtech-mobility.de\/#website","url":"https:\/\/valtech-mobility.de\/","name":"Valtech Mobility","description":"Some Cars Are Smarter Than Others.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valtech-mobility.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/pages\/18790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/comments?post=18790"}],"version-history":[{"count":1,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/pages\/18790\/revisions"}],"predecessor-version":[{"id":24207,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/pages\/18790\/revisions\/24207"}],"up":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/pages\/18762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media\/16652"}],"wp:attachment":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/media?parent=18790"}],"wp:term":[{"taxonomy":"seitenkategorie","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/seitenkategorie?post=18790"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/topic?post=18790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}