{"id":138,"count":1,"description":"","link":"https:\/\/valtech-mobility.de\/en\/category\/news\/sdv-blog-en\/","name":"SDV-Blog-en","slug":"sdv-blog-en","taxonomy":"category","parent":24,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SDV-Blog-en Archive - Valtech Mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SDV-Blog-en Archive - Valtech Mobility\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Valtech Mobility\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/category\\\/news-en\\\/sdv-news-en\\\/\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/category\\\/news-en\\\/sdv-news-en\\\/\",\"name\":\"SDV-Blog-en Archive - Valtech Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/category\\\/news-en\\\/sdv-news-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/category\\\/news-en\\\/sdv-news-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/valtech-mobility.de\\\/en\\\/category\\\/news-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SDV-Blog-en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valtech-mobility.de\\\/#website\",\"url\":\"https:\\\/\\\/valtech-mobility.de\\\/\",\"name\":\"Valtech Mobility\",\"description\":\"Some Cars Are Smarter Than Others.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valtech-mobility.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SDV-Blog-en Archive - Valtech Mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/","og_locale":"en_US","og_type":"article","og_title":"SDV-Blog-en Archive - Valtech Mobility","og_url":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/","og_site_name":"Valtech Mobility","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/","url":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/","name":"SDV-Blog-en Archive - Valtech Mobility","isPartOf":{"@id":"https:\/\/valtech-mobility.de\/#website"},"breadcrumb":{"@id":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/sdv-news-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/valtech-mobility.de\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/valtech-mobility.de\/en\/category\/news-en\/"},{"@type":"ListItem","position":3,"name":"SDV-Blog-en"}]},{"@type":"WebSite","@id":"https:\/\/valtech-mobility.de\/#website","url":"https:\/\/valtech-mobility.de\/","name":"Valtech Mobility","description":"Some Cars Are Smarter Than Others.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valtech-mobility.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/categories\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/categories\/24"}],"wp:post_type":[{"href":"https:\/\/valtech-mobility.de\/en\/wp-json\/wp\/v2\/posts?categories=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}